{"id":4398,"date":"2020-10-13T00:00:00","date_gmt":"2020-10-13T00:00:00","guid":{"rendered":"https:\/\/www.imovirtual.com\/noticias2\/2020\/10\/13\/alojamento-local-deixa-de-pagar-impostos\/"},"modified":"2020-10-13T00:00:00","modified_gmt":"2020-10-13T00:00:00","slug":"alojamento-local-deixa-de-pagar-impostos","status":"publish","type":"post","link":"https:\/\/www.imovirtual.com\/noticias\/novidades\/alojamento-local-deixa-de-pagar-impostos\/","title":{"rendered":"Casas retiradas do Alojamento Local deixam de pagar imposto sobre mais-valias"},"content":{"rendered":"<p class=\"css-8qfla4\">\n<p class=\"css-m5h6m0 edperro0\">\n<p>As casas que sejam retiradas do Alojamento Local (AL) deixam de estar obrigadas ao pagamento do imposto sobre as mais-valias. Esta medida est\u00e1 inserida na proposta do Or\u00e7amento do Estado para 2021.<\/p>\n<p>No documento entregue no Parlamento, o Governo prev\u00ea que todas as casas que deixem de ser de Alojamento Local ou at\u00e9 mesmo de outra atividade empresarial, deixem de pagar imposto sobre as mais-valias.<\/p>\n<p>\u00c9 alterado assim o regime fiscal da afeta\u00e7\u00e3o e desafeta\u00e7\u00e3o dos im\u00f3veis alocados a atividades empresariais.<\/p>\n<p>Caso a casa seja retirada do Alojamento Local, os contribuintes ficam obrigados a acrescer ao rendimento tribut\u00e1vel os custos que tenham j\u00e1 deduzidos no \u00e2mbito da atividade (quatros presta\u00e7\u00f5es anuais). Paralelamente, \u00e9 criada uma regra anti-abuso, ou seja, isto caso haja aliena\u00e7\u00e3o dos im\u00f3veis durante os tr\u00eas anos posteriores \u00e0 transfer\u00eancia para o cunho individual.<\/p>\n<p>O Or\u00e7amento de Estado para 2021 contempla 10 milh\u00f5es de euros, provenientes da parte da coleta do IRS para o Instituto da habita\u00e7\u00e3o e da Reabilita\u00e7\u00e3o Urbana (IHRU).<\/p>\n<\/p>\n<div class=\"css-h5fkc8\"><strong>Ultima actualiza\u00e7\u00e3o:<\/strong> 13 outubro 2020<\/div>\n","protected":false},"excerpt":{"rendered":"<p>As casas que sejam retiradas do Alojamento Local (AL) deixam de estar obrigadas ao pagamento do imposto sobre as mais-valias. Esta medida est\u00e1 inserida na proposta do Or\u00e7amento do Estado para 2021. No documento entregue no Parlamento, o Governo prev\u00ea que todas as casas que deixem de ser de Alojamento Local ou at\u00e9 mesmo de &hellip;<\/p>\n","protected":false},"author":3,"featured_media":4399,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novidades"],"_links":{"self":[{"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/posts\/4398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/comments?post=4398"}],"version-history":[{"count":0,"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/posts\/4398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/media\/4399"}],"wp:attachment":[{"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/media?parent=4398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/categories?post=4398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.imovirtual.com\/noticias\/wp-json\/wp\/v2\/tags?post=4398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}